{"id":10616,"date":"2023-12-06T18:05:00","date_gmt":"2023-12-06T10:05:00","guid":{"rendered":"https:\/\/li-on.biz\/?p=10616"},"modified":"2024-05-29T18:06:01","modified_gmt":"2024-05-29T10:06:01","slug":"cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/","title":{"rendered":"COP28\u805a\u7126\u4e8e\u4e94\u79cd\u6c14\u5019\u53d8\u8fc1\u89e3\u51b3\u65b9\u6848"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u5730\u7403\u6c14\u5019\u6b63\u5728\u8fc5\u901f\u53d8\u5316\uff0c\u9700\u8981\u91c7\u53d6\u7d27\u6025\u884c\u52a8\u4ee5\u907f\u514d\u5bf9\u4eba\u7c7b\u548c\u5927\u81ea\u7136\u9020\u6210\u5177\u7834\u574f\u6027\u7684\u540e\u679c\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u90a3\u4e48\u8fd9\u4e9b\u300c\u89e3\u51b3\u65b9\u6848\u300d\u6709\u54ea\u4e9b\uff1f\u8fdb\u5c55\u5982\u4f55\uff1f<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u51cf\u5c11\u5316\u77f3\u71c3\u6599\uff1a\u6700\u91cd\u8981\u200b\u200b\u7684\u662f\u51cf\u5c11\u5316\u77f3\u71c3\u6599\uff08\u7164\u70ad\u3001\u77f3\u6cb9\u548c\u5929\u7136\u6c14\uff09\u7684\u71c3\u70e7\uff0c\u5360\u5168\u7403\u5bfc\u81f4\u6e29\u5ba4\u6548\u5e94\u7684\u6e29\u5ba4\u6c14\u4f53\u6392\u653e\u603b\u91cf\u7684\u56db\u5206\u4e4b\u4e09\u4ee5\u4e0a\u3002\u56e0\u6b64\uff0c\u8bb8\u591a\u653f\u5e9c\u3001\u79d1\u5b66\u5bb6\u548c\u4e13\u4e1a\u4eba\u58eb\u5e0c\u671b\u5728COP28\u770b\u5230\u5173\u4e8e\u9010\u6b65\u6dd8\u6c70\u6c61\u67d3\u6027\u5316\u77f3\u71c3\u6599\u7684\u5168\u7403\u534f\u8bae\u3002\u56fd\u9645\u80fd\u6e90\u603b\u7f72(IEA)\u8868\u793a\uff0c\u5168\u7403\u5bf9\u7164\u70ad\u3001\u77f3\u6cb9\u548c\u5929\u7136\u6c14\u7684\u9700\u6c42\u9884\u8ba1\u57282030\u5e74\u524d\u8fbe\u5230\u5cf0\u503c\u3002\u4f46\u8fd9\u8fdc\u8fdc\u4e0d\u8db3\u4ee5\u5b9e\u73b02015\u5e74\u5df4\u9ece\u534f\u5b9a\u7684\u6c14\u5019\u76ee\u6807\u3002<\/li>\n\n\n\n<li>\u589e\u52a0\u300c\u518d\u751f\u80fd\u6e90\u300d\uff1a\u4e16\u754c\u4e0a\u6709\u5927\u91cf\u6e05\u6d01\u3001\u518d\u751f\u80fd\u6e90\u7684\u66ff\u4ee3\u6765\u6e90\uff0c\u4f8b\u5982\u98ce\u80fd\u548c\u592a\u9633\u80fd\u3002\u968f\u8457\u6210\u672c\u5927\u5e45\u4e0b\u964d\uff0c\u518d\u751f\u80fd\u6e90\u5728\u4e16\u754c\u8bb8\u591a\u5730\u533a\u84ec\u52c3\u53d1\u5c55\uff0c\u751a\u81f3\u6bd4IEA\u9884\u671f\u7684\u8fd8\u8981\u5feb\u3002 2022\u5e74\uff0c\u592a\u9633\u80fd\u53d1\u7535\u91cf\u6bd42015\u5e74\u589e\u52a0\u4e94\u500d\uff0c\u800c\u98ce\u529b\u53d1\u7535\u91cf\u5c06\u589e\u52a02.5\u500d\u3002\u6839\u636e\u7f8e\u56fd\u7814\u7a76\u673a\u6784RMI\uff0c\u52302030\u5e74\uff0c\u98ce\u80fd\u548c\u592a\u9633\u80fd\u63d0\u4f9b\u7684\u7535\u529b\u5c06\u4ece\u76ee\u524d\u768412%\u589e\u52a0\u81f3\u4e09\u5206\u4e4b\u4e00\u4ee5\u4e0a\u3002<\/li>\n\n\n\n<li>\u6539\u7528\u7535\u52a8\u8f66\uff1a\u9053\u8def\u8fd0\u8f93\u6392\u653e\u91cf\u7ea6\u5360\u5168\u7403\u6e29\u5ba4\u6c14\u4f53\u6392\u653e\u91cf\u768410%\uff0c\u4e3b\u8981\u6765\u6e90\u4e3a\u71c3\u70e7\u6c7d\u6cb9\u548c\u67f4\u6cb9\u7684\u6392\u653e\u3002\u5728\u6b27\u6d32\u548c\u7f8e\u56fd\uff0c\u4e0e\u71c3\u6cb9\u6c7d\u8f66\u76f8\u6bd4\uff0c\u7535\u52a8\u8f66\u5728\u6574\u4e2a\u751f\u547d\u5468\u671f\u4e2d\u7684\u6392\u653e\u91cf\u5e73\u5747\u51cf\u5c11\u7ea6\u4e09\u5206\u4e4b\u4e8c\u3002\u867d\u7136\u7535\u52a8\u8f66\u4e0d\u4f1a\u6392\u653e\u5bfc\u81f4\u5730\u7403\u53d8\u6696\u7684\u70df\u96fe\uff0c\u4f46\u5b83\u4eec\u5e76\u975e\u5b8c\u5168\u96f6\u6392\u653e\u3002\u968f\u7740\u7535\u529b\u53d8\u5f97\u66f4\u52a0\u6e05\u6d01\uff0c\u7535\u52a8\u8f66\u5c06\u6bd4\u6c7d\u6cb9\u548c\u67f4\u6cb9\u6c7d\u8f66\u5177\u6709\u66f4\u5927\u7684\u6392\u653e\u4f18\u52bf\u3002<\/li>\n\n\n\n<li>\u89e3\u51b3\u7532\u70f7\u95ee\u9898\uff1a\u5168\u7403\u6696\u5316\u7ea6\u670930%\u662f\u7531\u4e8e\u7532\u70f7\u6392\u653e\u9020\u6210\u7684\u3002\u7532\u70f7\u5728\u5927\u6c14\u4e2d\u7684\u542b\u91cf\u8fdc\u4f4e\u4e8e\u4e8c\u6c27\u5316\u78b3\uff0c\u4f46\u5728\u8fd120\u5e74\u95f4\uff0c\u7532\u70f7\u6696\u5316\u7684\u5a01\u529b\u5927\u7ea6\u662f\u4e8c\u6c27\u5316\u78b3\u768480\u500d\uff0c\u8fd9\u610f\u5473\u7740\u51cf\u5c11\u7532\u70f7\u6392\u653e\u53ef\u80fd\u662f\u77ed\u671f\u5185\u51cf\u7f13\u6696\u5316\u6700\u6709\u6548\u7684\u65b9\u6cd5\u4e4b\u4e00\u3002\u56e0\u6b64\uff0c\u6709\u8d85\u8fc7150\u4e2a\u56fd\u5bb6\u5df2\u540c\u610f\u57282030\u5e74\u5c06\u7532\u70f7\u6392\u653e\u91cf\u51cf\u5c1130%\u3002\u4f46\u4f5c\u4e3a\u5168\u7403\u6700\u5927\u7684\u7532\u70f7\u6392\u653e\u56fd\u4e2d\u56fd\u4ecd\u5c1a\u672a\u7b7e\u7f72\u3002<\/li>\n\n\n\n<li>\u78b3\u6355\u6349\uff1a\u82e5\u8981\u6e29\u5347\u63a7\u5236\u5728\u6444\u6c0f1.5\u5ea6\u5185\uff0c\u51e0\u4e4e\u80af\u5b9a\u9700\u8981\u4ece\u6e90\u5934\u6355\u83b7\u4e00\u4e9b\u4e8c\u6c27\u5316\u78b3\uff0c\u6216\u76f4\u63a5\u4ece\u5927\u6c14\u4e2d\u83b7\u53d6\u3002\u7136\u800c\uff0c\u8981\u5c06\u5168\u7403\u6e29\u5347\u63a7\u5236\u5728\u6444\u6c0f1.5\u5ea6\u7684\u65f6\u95f4\u5df2\u7ecf\u4e0d\u591a\u4e86\uff0c\u4e14\u8fd8\u6709\u4e00\u4e9b\u4ea7\u4e1a\u8fd8\u65e0\u6cd5\u8f7b\u6613\u8131\u78b3\uff0c\u4f8b\u5982\u519c\u4e1a\u548c\u822a\u7a7a\u4e1a\u3002\u56e0\u6b64\uff0c\u4e8c\u6c27\u5316\u78b3\u53ef\u4ee5\u900f\u8fc7\u81ea\u7136\u6216\u4eba\u5de5\u8fc7\u7a0b\u6355\u83b7\u3002<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u8d44\u6599\u6765\u6e90: BBC<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5730\u7403\u6c23\u5019\u6b63\u5728\u8fc5\u901f\u8b8a\u5316\uff0c\u9700\u8981\u63a1\u53d6\u7dca\u6025\u884c\u52d5\u4ee5\u907f\u514d\u5c0d\u4eba\u985e\u548c\u5927\u81ea\u7136\u9020\u6210\u5177\u7834\u58de\u6027\u7684\u5f8c\u679c\u3002 \u90a3\u9ebc\u9019\u4e9b\u300c\u89e3\u6c7a\u65b9\u6848\u300d\u6709\u54ea\u4e9b\uff1f\u9032 [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-10616","post","type-post","status-publish","format-standard","hentry","category-environmental-related-reports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"\u5730\u7403\u6c23\u5019\u6b63\u5728\u8fc5\u901f\u8b8a\u5316\uff0c\u9700\u8981\u63a1\u53d6\u7dca\u6025\u884c\u52d5\u4ee5\u907f\u514d\u5c0d\u4eba\u985e\u548c\u5927\u81ea\u7136\u9020\u6210\u5177\u7834\u58de\u6027\u7684\u5f8c\u679c\u3002 \u90a3\u9ebc\u9019\u4e9b\u300c\u89e3\u6c7a\u65b9\u6848\u300d\u6709\u54ea\u4e9b\uff1f\u9032 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/cop28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T10:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T10:06:01+00:00\" \/>\n<meta name=\"author\" content=\"bosunbiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"bosunbiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/\"},\"author\":{\"name\":\"bosunbiz\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/20d593d026c26e16c4f8b13c713e5f34\"},\"headline\":\"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848\",\"datePublished\":\"2023-12-06T10:05:00+00:00\",\"dateModified\":\"2024-05-29T10:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u74b0\u5883\u751f\u614b\u76f8\u95dc\u5831\u5c0e\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/\",\"name\":\"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2023-12-06T10:05:00+00:00\",\"dateModified\":\"2024-05-29T10:06:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u74b0\u5883\u751f\u614b\u76f8\u95dc\u5831\u5c0e\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/environmental-related-reports\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/20d593d026c26e16c4f8b13c713e5f34\",\"name\":\"bosunbiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"caption\":\"bosunbiz\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/bosunbiz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280","og_description":"\u5730\u7403\u6c23\u5019\u6b63\u5728\u8fc5\u901f\u8b8a\u5316\uff0c\u9700\u8981\u63a1\u53d6\u7dca\u6025\u884c\u52d5\u4ee5\u907f\u514d\u5c0d\u4eba\u985e\u548c\u5927\u81ea\u7136\u9020\u6210\u5177\u7834\u58de\u6027\u7684\u5f8c\u679c\u3002 \u90a3\u9ebc\u9019\u4e9b\u300c\u89e3\u6c7a\u65b9\u6848\u300d\u6709\u54ea\u4e9b\uff1f\u9032 [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/cop28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2023-12-06T10:05:00+00:00","article_modified_time":"2024-05-29T10:06:01+00:00","author":"bosunbiz","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"bosunbiz","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/"},"author":{"name":"bosunbiz","@id":"https:\/\/li-on.biz\/#\/schema\/person\/20d593d026c26e16c4f8b13c713e5f34"},"headline":"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848","datePublished":"2023-12-06T10:05:00+00:00","dateModified":"2024-05-29T10:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u74b0\u5883\u751f\u614b\u76f8\u95dc\u5831\u5c0e"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/","url":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/","name":"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848 - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2023-12-06T10:05:00+00:00","dateModified":"2024-05-29T10:06:01+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/cop28%e8%81%9a%e7%84%a6%e6%96%bc%e4%ba%94%e7%a8%ae%e6%b0%a3%e5%80%99%e8%ae%8a%e9%81%b7%e8%a7%a3%e6%b1%ba%e6%96%b9%e6%a1%88\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u74b0\u5883\u751f\u614b\u76f8\u95dc\u5831\u5c0e","item":"https:\/\/li-on.biz\/category\/environmental-related-reports\/"},{"@type":"ListItem","position":2,"name":"COP28\u805a\u7126\u65bc\u4e94\u7a2e\u6c23\u5019\u8b8a\u9077\u89e3\u6c7a\u65b9\u6848"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/20d593d026c26e16c4f8b13c713e5f34","name":"bosunbiz","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","caption":"bosunbiz"},"url":"https:\/\/li-on.biz\/zh\/author\/bosunbiz\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/10616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=10616"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/10616\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=10616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=10616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=10616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}