{"id":11648,"date":"2022-05-25T15:13:00","date_gmt":"2022-05-25T07:13:00","guid":{"rendered":"https:\/\/li-on.biz\/?p=11648"},"modified":"2024-09-25T15:14:34","modified_gmt":"2024-09-25T07:14:34","slug":"%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/","title":{"rendered":"\u7ec8\u7ed3\u5bf9\u4fc4\u80fd\u6e90\u4f9d\u8d56 \u6b27\u76df\u63d09.5\u5146\u65b0\u8ba1\u753b \u52a0\u901f\u80fd\u6e90\u8f6c\u578b"},"content":{"rendered":"<p>\u300aEuractiv\u300b\u62a5\u5bfc\uff0c\u6b27\u76df\u6267\u59d4\u4f1a\u4e0a\u5468\u4e09\uff0818\u65e5\uff09\u6b63\u5f0f\u63d0\u51fa\u300cREPowerEU\u300d\u8ba1\u753b\uff0c\u5c06\u6295\u8d443000\u4ebf\u6b27\u5143\uff08\u7ea6\u65b0\u53f0\u5e019.5\u5146\uff09\uff0c\u8fbe\u62102027\u5e74\u505c\u6b62\u5411\u4fc4\u7f57\u65af\u8fdb\u53e3\u80fd\u6e90\uff0c\u5e76\u52a0\u901f\u63a8\u52a8\u80fd\u6e90\u8f6c\u578b\u7b49\u76ee\u6807\u3002\u4e0d\u8fc7\u6267\u59d4\u4f1a\u4e5f\u627f\u8ba4\uff0c\u8981\u53d6\u4ee3\u4fc4\u7f57\u65af\u77f3\u6cb9\u548c\u5929\u7136\u6c14\uff0c\u6b27\u76df\u5f97\u5bf9\u65b0\u7684\u5316\u77f3\u71c3\u6599\u57fa\u7840\u8bbe\u65bd\u8fdb\u884c\u77ed\u671f\u6295\u8d44\uff0c\u6b64\u4e3e\u4e5f\u5f15\u53d1\u73af\u4fdd\u56e2\u4f53\u6279\u8bc4\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u805a\u7126\u518d\u751f\u80fd\u6e90\uff1a\u53d1\u7535\u5360\u6bd4\u63d0\u9ad85%\u3001\u65b0\u4f4f\u5b85\u5f3a\u5236\u52a0\u88c5\u592a\u9633\u80fd\u677f<\/h3>\n\n\n\n<p>REPowerEU\u7684\u8ba1\u753b\u5185\u5bb9\u4e3b\u8981\u5206\u6210\u4e09\u5927\u90e8\u5206\uff1a\u8282\u80fd\u3001\u4fc3\u8fdb\u518d\u751f\u80fd\u6e90\u53d1\u5c55\uff0c\u4ee5\u53ca\u4f7f\u6b27\u6d32\u77f3\u6cb9\u548c\u5929\u7136\u6c14\u4f9b\u7ed9\u591a\u6837\u5316\u3002\u5176\u4e2d\u5177\u4f53\u63d0\u6848\u5305\u542b\uff0c\u5c06\u6b27\u76df\u57282030\u5e74\u4e4b\u524d\u8981\u8fbe\u5230\u7684\u518d\u751f\u80fd\u6e90\u53d1\u7535\u5360\u6bd4\u76ee\u6807\uff0c\u4ece\u53bb\u5e74\u63d0\u51fa\u768440%\u63d0\u9ad8\u523045%\uff1b\u5e76\u5c06\u80fd\u6e90\u6548\u7387\u76ee\u6807\u4ece2030\u5e74\u4e4b\u524d\u51cf\u5c119%\u80fd\u6e90\u6d88\u8d39\uff08\u4ee52020\u5e74\u4e3a\u57fa\u51c6\uff09\uff0c\u63d0\u5347\u5230\u51cf\u5c1113%\u3002<\/p>\n\n\n\n<p>\u6b64\u5916\uff0cREPowerEU\u66f4\u63d0\u51fa\u5206\u522b\u57282025\u5e74\u548c2029\u5e74\u524d\uff0c\u5c06\u592a\u9633\u80fd\u677f\u5f3a\u5236\u52a0\u88c5\u4e8e\u516c\u5171\u5efa\u7b51\u548c\u65b0\u5efa\u4f4f\u5b85\u7684\u63d0\u6848\u3002<\/p>\n\n\n\n<p>\u4e00\u4f4d\u6b27\u76df\u9ad8\u7ea7\u5b98\u5458\u8868\u793a\uff0c\u6839\u636e\u8be5\u8ba1\u753b\uff0c\u5230\u4eca\uff082022\uff09\u5e74\u5e95\uff0c\u6b27\u76df\u5bf9\u4fc4\u7f57\u65af\u5929\u7136\u6c14\u7684\u4f7f\u7528\u91cf\u5c06\u5148\u51cf\u5c112\/3\u3002\u968f\u540e\uff0c\u7531\u4e8e\u5efa\u7acb\u518d\u751f\u80fd\u6e90\u4ea7\u80fd\u9700\u8981\u65f6\u95f4\uff0c\u6b27\u76df\u5c06\u6e10\u8fdb\u3001\u7ebf\u6027\u5730\u8fdb\u4e00\u6b65\u51cf\u5c11\u4f7f\u7528\u91cf\u3002<\/p>\n\n\n\n<p>\u6839\u636e\u6b27\u76df\u6267\u59d4\u4f1a\u7684\u63d0\u6848\uff0c\u5feb\u901f\u548c\u5927\u89c4\u6a21\u90e8\u7f72\u518d\u751f\u80fd\u6e90\uff0c\u5c24\u5176\u662f\u592a\u9633\u80fd\uff0c\u662fREPowerEU\u7684\u6838\u5fc3\u3002\u4e3a\u4e86\u52a0\u5feb\u90e8\u7f72\uff0c\u6b27\u76df\u6267\u59d4\u4f1a\u5e0c\u671b\u7b80\u5316\u8bb8\u53ef\u7a0b\u5e8f\uff0c\u5c06\u65b0\u7684\u98ce\u80fd\u548c\u592a\u9633\u80fd\u4e13\u6848\u89c6\u4e3a\u300c\u9ad8\u5ea6\u4f18\u5148\u516c\u5171\u5229\u76ca\u300d\uff0c\u5e76\u5728\u56fd\u5bb6\u5c42\u7ea7\u4e0a\uff0c\u5728\u73af\u5883\u98ce\u9669\u4f4e\u7684\u5730\u533a\u5212\u51fa\u300c\u9996\u9009\u300d\u533a\u57df\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u4fc3\u6cb9\u6c14\u4f9b\u7ed9\u591a\u6837\u5316 \u6b27\u76df\u5c06\u4e0e\u7f8e\u52a0\u7b49\u56fd\u7b7e\u91c7\u8d2d\u5408\u7ea6<\/h3>\n\n\n\n<p>\u6b27\u76df\u4e5f\u63d0\u51fa\u8981\u5728\u77ed\u671f\u5185\u7b7e\u8ba2\u65b0\u7684\u5316\u77f3\u71c3\u6599\u91c7\u8d2d\u5408\u7ea6\uff0c\u4f7f\u6b27\u6d32\u77f3\u6cb9\u548c\u5929\u7136\u6c14\u4f9b\u7ed9\u591a\u6837\u5316\uff0c\u4ee5\u53d6\u4ee3\u4fc4\u7f57\u65af\u7684\u5316\u77f3\u71c3\u6599\u3002\u5176\u4e2d\u5305\u62ec\u4e0e\u7f8e\u56fd\u3001\u52a0\u62ff\u5927\u548c\u5176\u4ed6\u56fd\u5bb6\u8fbe\u6210\u6db2\u5316\u5929\u7136\u6c14\u534f\u8bae\uff0c\u5e76\u4e3a\u5e0c\u671b\u53c2\u4e0e\u7684\u56fd\u5bb6\u5efa\u7acb\u8054\u5408\u91c7\u8d2d\u5e73\u53f0\u3002<\/p>\n\n\n\n<p>\u8d44\u6599\u6765\u6e90:\u00a0\u73af\u5883\u8d44\u8baf\u4e2d\u5fc3\u00a0(https:\/\/e-info.org.tw\/node\/234148)<\/p>","protected":false},"excerpt":{"rendered":"<p>\u300aEuractiv\u300b\u5831\u5c0e\uff0c\u6b50\u76df\u57f7\u59d4\u6703\u4e0a\u5468\u4e09\uff0818\u65e5\uff09\u6b63\u5f0f\u63d0\u51fa\u300cREPowerEU\u300d\u8a08\u756b\uff0c\u5c07\u6295\u8cc73000\u5104\u6b50\u5143\uff08 [&hellip;]<\/p>","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-11648","post","type-post","status-publish","format-standard","hentry","category-eu-energy-use"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"\u300aEuractiv\u300b\u5831\u5c0e\uff0c\u6b50\u76df\u57f7\u59d4\u6703\u4e0a\u5468\u4e09\uff0818\u65e5\uff09\u6b63\u5f0f\u63d0\u51fa\u300cREPowerEU\u300d\u8a08\u756b\uff0c\u5c07\u6295\u8cc73000\u5104\u6b50\u5143\uff08 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4-\u6b50\u76df\u63d09-5\u5146\u65b0\u8a08\u756b-\u52a0\u901f\u80fd\u6e90\u8f49\u578b\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T07:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T07:14:34+00:00\" \/>\n<meta name=\"author\" content=\"bosunbiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"bosunbiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/\"},\"author\":{\"name\":\"bosunbiz\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/24edfa40d28ecbd71af7a963836ff729\"},\"headline\":\"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b\",\"datePublished\":\"2022-05-25T07:13:00+00:00\",\"dateModified\":\"2024-09-25T07:14:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u6b50\u76df\u80fd\u6e90\u4f7f\u7528\u7522\u54c1\u6307\u4ee4\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/\",\"name\":\"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2022-05-25T07:13:00+00:00\",\"dateModified\":\"2024-09-25T07:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u6b50\u76df\u80fd\u6e90\u4f7f\u7528\u7522\u54c1\u6307\u4ee4\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/eu-energy-use\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/24edfa40d28ecbd71af7a963836ff729\",\"name\":\"bosunbiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g\",\"caption\":\"bosunbiz\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/bosunbiz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280","og_description":"\u300aEuractiv\u300b\u5831\u5c0e\uff0c\u6b50\u76df\u57f7\u59d4\u6703\u4e0a\u5468\u4e09\uff0818\u65e5\uff09\u6b63\u5f0f\u63d0\u51fa\u300cREPowerEU\u300d\u8a08\u756b\uff0c\u5c07\u6295\u8cc73000\u5104\u6b50\u5143\uff08 [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4-\u6b50\u76df\u63d09-5\u5146\u65b0\u8a08\u756b-\u52a0\u901f\u80fd\u6e90\u8f49\u578b\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2022-05-25T07:13:00+00:00","article_modified_time":"2024-09-25T07:14:34+00:00","author":"bosunbiz","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"bosunbiz","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/"},"author":{"name":"bosunbiz","@id":"https:\/\/li-on.biz\/#\/schema\/person\/24edfa40d28ecbd71af7a963836ff729"},"headline":"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b","datePublished":"2022-05-25T07:13:00+00:00","dateModified":"2024-09-25T07:14:34+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u6b50\u76df\u80fd\u6e90\u4f7f\u7528\u7522\u54c1\u6307\u4ee4"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/","url":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/","name":"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2022-05-25T07:13:00+00:00","dateModified":"2024-09-25T07:14:34+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/%e7%b5%82%e7%b5%90%e5%b0%8d%e4%bf%84%e8%83%bd%e6%ba%90%e4%be%9d%e8%b3%b4-%e6%ad%90%e7%9b%9f%e6%8f%909-5%e5%85%86%e6%96%b0%e8%a8%88%e7%95%ab-%e5%8a%a0%e9%80%9f%e8%83%bd%e6%ba%90%e8%bd%89%e5%9e%8b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u6b50\u76df\u80fd\u6e90\u4f7f\u7528\u7522\u54c1\u6307\u4ee4","item":"https:\/\/li-on.biz\/category\/eu-energy-use\/"},{"@type":"ListItem","position":2,"name":"\u7d42\u7d50\u5c0d\u4fc4\u80fd\u6e90\u4f9d\u8cf4 \u6b50\u76df\u63d09.5\u5146\u65b0\u8a08\u756b \u52a0\u901f\u80fd\u6e90\u8f49\u578b"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/24edfa40d28ecbd71af7a963836ff729","name":"bosunbiz","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29db3691b907f57c9e6a88dbfff7a8275a4b3b5a0d220490a28a5e56f22e3039?s=96&d=mm&r=g","caption":"bosunbiz"},"url":"https:\/\/li-on.biz\/zh\/author\/bosunbiz\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/11648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=11648"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/11648\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=11648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=11648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=11648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}