{"id":6204,"date":"2010-03-12T19:19:17","date_gmt":"2010-03-12T11:19:17","guid":{"rendered":"https:\/\/li-on.biz\/?p=6204"},"modified":"2024-02-02T15:00:04","modified_gmt":"2024-02-02T07:00:04","slug":"it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/","title":{"rendered":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u4e0e\u73af\u5883\u95ee\u9898"},"content":{"rendered":"<p>IBM\u8ba4\u4e3a\uff0cIT\u5728\u80fd\u6e90\u7ba1\u7406\u4e2d\u7684\u4f5c\u7528\u5df2\u7ecf\u5f00\u59cb\u9010\u6b65\u88ab\u8ba4\u53ef\uff0c\u91c7\u7528\u7efc\u5408\u6027\u667a\u6167\u7cfb\u7edf\u6765\u89e3\u51b3\u80fd\u6e90\u548c\u73af\u5883\u95ee\u9898\u7684\u65f6\u673a\u5df2\u7ecf\u6210\u719f\u3002<\/p>\n\n\n\n<p>\u793e\u4f1a\u5bf9\u73af\u4fdd\u95ee\u9898\u7684\u65e5\u76ca\u5173\u6ce8\u3001\u65e5\u6e10\u52a0\u91cd\u7684\u516c\u4f17\u8206\u8bba\u538b\u529b\u3001\u66f4\u4e25\u683c\u7684\u653f\u7b56\u53ca\u884c\u4e1a\u89c4\u5b9a\uff0c\u4ee5\u53ca\u4e1a\u5185\u5bf9\u524a\u51cf\u9ad8\u6602\u80fd\u6e90\u6210\u672c\u7684\u81ea\u53d1\u9700\u6c42\uff0c\u90fd\u5728\u4fc3\u4f7f\u5168\u7403\u4f01\u4e1a\u8f6c\u53d8\u539f\u6709\u7684\u4e1a\u52a1\u8fd0\u8425\u65b9\u5f0f\u3002\u5f88\u591a\u884c\u4e1a\u90fd\u5728\u7ecf\u5386\u7740\u4ece\u7b26\u5408\u73af\u5883\u8981\u6c42\u5230\u73af\u5883\u98ce\u9669\u7ba1\u7406\uff0c\u518d\u5230\u957f\u671f\u53ef\u6301\u7eed\u53d1\u5c55\u7684\u4e09\u4e2a\u53d1\u5c55\u9636\u6bb5\u3002<\/p>\n\n\n\n<p>\u4e3a\u4e86\u52a0\u901f\u8fd9\u79cd\u8f6c\u53d8\uff0c\u4f01\u4e1a\u672c\u8eab\u5df2\u7ecf\u4e0d\u4ec5\u4ec5\u53ea\u662f\u4ece\u964d\u4f4eIT\u80fd\u6e90\u8017\u7528\u4ee5\u53ca\u8d44\u6599\u4e2d\u5fc3\u5f3a\u5316\u7684\u89d2\u5ea6\u7740\u773c\uff0cIT\u751a\u81f3\u5f00\u59cb\u6210\u4e3a\u89e3\u51b3\u80fd\u6e90\u95ee\u9898\u7684\u5173\u952e\uff0c\u540c\u65f6\uff0cIT\u4e5f\u5df2\u7ecf\u9010\u6b65\u6446\u8131\u4e86\u80fd\u6e90\u6d88\u8017\u5927\u6237\u548c\u73af\u5883\u6740\u624b\u7684\u6076\u540d\u3002 IBM\u8f6f\u4f53\u96c6\u56e2Tivoli\u8f6f\u4f53\u5168\u7403\u603b\u7ecf\u7406Alfred Zollar\u8ba4\u4e3a\uff0c\u867d\u7136IT\u5236\u9020\u4e86\u5168\u74032%\u7684\u78b3\u6392\u653e\u91cf\uff0c\u4f46\u5374\u53ef\u4ee5\u5e2e\u52a9\u63a7\u5236\u548c\u51cf\u5c11\u5176\u4ed6\u6d3b\u52a8\u548c\u884c\u4e1a\u4ea7\u751f\u768498%\u7684\u78b3\u6392\u653e\u91cf\uff1b\u4e8b\u5b9e\u4e0a\uff0c\u5728\u73af\u5883\u5e02\u573a\u89c4\u5212\u3001\u751f\u6001\u901a\u4fe1\u548c\u78b3\u7ba1\u7406\u7b49\u65b9\u9762\u90fd\u9700\u8981IT\u7684\u5168\u9762\u5e2e\u52a9\u3002<\/p>\n\n\n\n<p>\u201cIT\u5728\u80fd\u6e90\u7ba1\u7406\u4e2d\u7684\u4f5c\u7528\u5df2\u7ecf\u88ab\u9010\u6b65\u8ba4\u53ef\uff0c\u91c7\u7528\u7efc\u5408\u6027\u667a\u6167\u7cfb\u7edf\u6765\u89e3\u51b3\u80fd\u6e90\u548c\u73af\u5883\u95ee\u9898\u7684\u65f6\u673a\u5df2\u7ecf\u6210\u719f\u3002\u201dAlfred Zollar\u8868\u793a\ufe30\u201cIBM\u5728\u63d0\u9ad8\u5f53\u524d\u7cfb\u7edf\u6548\u7387\u3001\u652f\u63f4\u5ba2\u6237\u2018\u7eff\u8272\u2019\u6218\u7565\u65b9\u9762\u7684\u8fdb\u7a0b\u4e5f\u5df2\u7ecf\u5f00\u59cb\u3002\u201d\u73b0\u5728\uff0c\u4eba\u4eec\u5f00\u59cb\u91c7\u7528\u65b0\u6280\u672f\u63d0\u9ad8\u5efa\u7b51\u7269\u3001\u8f66\u8f86\u548c\u5de5\u4e1a\u6d41\u7a0b\u7684\u80fd\u6548\uff1b\u91c7\u7528\u65b0\u65b9\u6cd5\u51cf\u5c11\u7a7a\u6c14\u6c61\u67d3\u548c\u6e29\u5ba4\u6c14\u4f53\u7684\u6392\u653e\uff1b\u5e76\u5f00\u59cb\u66f4\u5e7f\u6cdb\u4f7f\u7528\u53ef\u518d\u751f\u80fd\u6e90\uff0c\u800c\u8fd9\u4e9b\u4eba\u4eec\u5728\u80fd\u6e90\u4f9b\u5e94\u3001\u80fd\u6e90\u8282\u7ea6\u548c\u6c14\u5019\u4fdd\u62a4\u7b49\u65b9\u9762\u6240\u505a\u7684\u52aa\u529b\u65e0\u7591\u90fd\u9700\u8981IT\u7cfb\u7edf\u7684\u5e2e\u52a9\u3002<\/p>\n\n\n\n<p>\u76ee\u524d\uff0cIBM\u5ba3\u5e03\u9488\u5bf9\u80fd\u6e90\u548c\u73af\u5883\u6218\u7565\u5236\u5b9a\u4e86\u4e94\u9879\u8ba1\u753b\u3002\u9996\u5148\u662f\u8282\u80fd\u6280\u672f\u4e0e\u670d\u52a1\uff0c\u5176\u81f4\u529b\u4e8e\u901a\u8fc7\u865a\u62df\u5316\u3001\u667a\u6167\u7535\u6e90\u7ba1\u7406\u548c\u8282\u80fd\u8d44\u6599\u4e2d\u5fc3\u8bbe\u8ba1\u4e0e\u6574\u5408\u6765\u964d\u4f4e\u7528\u6237\u7684\u80fd\u6e90\u6210\u672c\u3002\u4e8b\u5b9e\u4e0a\uff0c\u5728\u53bb\u5e745\u6708\uff0cIBM\u5c31\u5ba3\u5e03\u5c06\u6bcf\u5e74\u518d\u6295\u516510\u4ebf\u7f8e\u5143\uff0c\u7528\u4e8e\u52a0\u901f\u8fd9\u65b9\u9762\u7684\u5de5\u4f5c\u3002<\/p>\n\n\n\n<p>\u5176\u6b21\u662f\u667a\u6167\u7535\u7f51\uff08Intelligent Utility Network\uff09\uff0c\u5168\u7403\u80fd\u6e90\u7f51\u8def\u6570\u4f4d\u5316\u6c34\u51c6\u7684\u4e0d\u65ad\u63d0\u9ad8\u521b\u9020\u4e86\u4e00\u79cd\u667a\u6167\u578b\u7f51\u8def\uff0c\u800cIBM\u7684\u667a\u6167\u7535\u7f51\u80fd\u591f\u652f\u6301\u80fd\u6e90\u516c\u5171\u8bbe\u65bd\u63d0\u9ad8\u80fd\u6e90\u6548\u7387\u5e76\u4f7f\u7528\u66f4\u591a\u7684\u53ef\u518d\u751f\u80fd\u6e90\u3002\u636eAlfred Zollar\u4ecb\u7ecd\uff0c\u667a\u6167\u7535\u7f51\u901a\u8fc7\u8fde\u63a5\u516c\u5171\u8bbe\u65bd\u5404\u91cd\u8981\u90e8\u4ef6\u7684\u8fde\u7eed\u611f\u5e94IP\u7f51\u8def\uff08\u4ece\u8bbe\u5907\u5230\u63a7\u5236\u7cfb\u7edf\u518d\u5230\u5e94\u7528\u548c\u5458\u5de5\uff09\uff0c\u4e3a\u7535\u529b\u4f9b\u5e94\u5546\u63d0\u4f9b\u51b3\u7b56\u652f\u63f4\uff1b\u540c\u65f6\uff0c\u5b83\u8fd8\u80fd\u5bf9\u516c\u5171\u8bbe\u65bd\u7684\u8d44\u4ea7\u548c\u8fd0\u884c\u8fdb\u884c\u4e0d\u95f4\u65ad\u5730\u76d1\u89c6\u548c\u56de\u9988\uff0c\u4ee5\u63d0\u9ad8\u7cfb\u7edf\u7684\u53ef\u9760\u6027\u3001\u7075\u6d3b\u6027\u548c\u8fd0\u884c\u6548\u7387\uff0c\u5e76\u589e\u5f3a\u4f01\u4e1a\u7684\u73af\u5883\u610f\u8bc6\u548c\u7ba1\u7406\u80fd\u529b\u3002<\/p>\n\n\n\n<p>\u7b2c\u4e09\u662f\u667a\u6167\u4ea4\u901a\u7cfb\u7edf\uff0c\u5176\u53ef\u4ee5\u5c06\u8d44\u8baf\u548c\u901a\u4fe1\u6280\u672f\u5e94\u7528\u4e8e\u4ea4\u901a\u57fa\u7840\u8bbe\u65bd\u548c\u8f66\u8f86\uff0c\u4ece\u800c\u6709\u6548\u5730\u7ba1\u7406\u62e5\u5835\u95ee\u9898\u3001\u51cf\u5c11\u78b3\u6392\u653e\u91cf\u3001\u6539\u5584\u516c\u4ea4\u7528\u6237\u7684\u4f53\u9a8c\uff0c\u5e76\u4f7f\u7528\u8d44\u8baf\u548c\u5206\u6790\u6765\u4f18\u5316\u4ea4\u901a\u7f51\u7edc\u3002\u7ecf\u7531\u667a\u6167\u4ea4\u901a\u7cfb\u7edf\u7684\u5e94\u7528\uff0c\u53ef\u4ee5\u5373\u65f6\u76d1\u89c6\u548c\u9884\u6d4b\u4e3b\u8981\u57ce\u533a\u9053\u8def\u7684\u62e5\u585e\u72b6\u51b5\uff0c\u4ece\u800c\u53ca\u65f6\u91c7\u53d6\u63aa\u65bd\u6765\u51cf\u5c11\u585e\u8f66\uff0c\u6bd4\u5982\u5411\u5728\u7279\u5b9a\u65f6\u95f4\u8fdb\u5165\u5e02\u4e2d\u5fc3\u7684\u8f66\u8f86\u9a7e\u9a76\u6536\u8d39\u3002 \u201c\u65af\u5fb7\u54e5\u5c14\u6469\u5e02\u5728\u91c7\u7528\u4e86IBM\u7684\u89e3\u51b3\u65b9\u6848\u540e\uff0c\u9ad8\u5cf0\u65f6\u6bb5\u7684\u4ea4\u901a\u62e5\u5835\u72b6\u51b5\u51cf\u5c11\u4e8625%\uff0c\u78b3\u6392\u653e\u91cf\u51cf\u5c11\u4e8615%\u3002\u201dAlfred Zollar\u4ecb\u7ecd\u8bf4\u3002<\/p>\n\n\n\n<p>\u6b64\u5916\uff0c\u4f5c\u4e3aBig Green Innovations\u8ba1\u753b\u4e2d\u7684\u4e00\u90e8\u5206\uff0cIBM\u6b63\u5728\u5c06\u7f51\u8def\u667a\u6167\u4ee5\u53ca\u516c\u5171\u4e8b\u4e1a\u548c\u4ea4\u901a\u57fa\u7840\u8bbe\u65bd\u7ba1\u7406\u65b9\u9762\u7684\u7ecf\u9a8c\u5e94\u7528\u4e8e\u6c34\u7ba1\u7406\u3002 \u201c\u6211\u4eec\u8fd8\u5c06\u5229\u7528\u5728\u5948\u7c73\u6280\u672f\u65b9\u9762\u7684\u4f18\u52bf\uff0c\u964d\u4f4e\u4ea7\u54c1\u7684\u5236\u9020\u6210\u672c\u3002\u201dAlfred Zollar\u8868\u793a\u3002<\/p>\n\n\n\n<p>\u6700\u540e\uff0c\u5c31\u662f\u78b3\u7ba1\u7406\uff0c\u5728\u201c\u78b3\u610f\u8bc6\u201d\u65e5\u76ca\u589e\u5f3a\u7684\u73af\u5883\u4e0b\uff0cIBM\u7814\u53d1\u4e86\u4e00\u7cfb\u5217\u78b3\u7ba1\u7406\u54a8\u8be2\u80fd\u529b\uff0c\u4ee5\u5e2e\u52a9\u5ba2\u6237\u4e86\u89e3\u548c\u7ba1\u7406\u672c\u4f01\u4e1a\u7684\u6e29\u5ba4\u6c14\u4f53\u6392\u653e\u91cf\uff0c\u5e76\u5236\u5b9a\u4e13\u95e8\u63aa\u65bd\u6765\u63a7\u5236\u548c\u7ba1\u7406\u5176\u4f9b\u5e94\u94fe\u3001\u5efa\u7b51\u65bd\u5de5\u3001IT\u548c\u4ea7\u54c1\u4e2d\u7684\u78b3\u8db3\u8ff9\u3002<\/p>\n\n\n\n<p>\u2013\u00a0\u53c2\u8003\u8d44\u6599\u6765\u6e90\uff1a\u65b0\u534e\u793e<\/p>\n\n\n\n<p>&#8211;&nbsp;\u8ca1\u5718\u6cd5\u4eba\u5851\u81a0\u5de5\u696d\u6280\u8853\u767c\u5c55\u4e2d\u5fc3\u8b6f<\/p>\n\n\n\n<p>&#8211;&nbsp;\u8b39\u4f9b\u53c3\u8003\uff0c\u8acb\u4ee5\u539f\u6587\u70ba\u4e3b<\/p>","protected":false},"excerpt":{"rendered":"<p>IBM\u8a8d\u70ba\uff0cIT\u5728\u80fd\u6e90\u7ba1\u7406\u4e2d\u7684\u4f5c\u7528\u5df2\u7d93\u958b\u59cb\u9010\u6b65\u88ab\u8a8d\u53ef\uff0c\u63a1\u7528\u7d9c\u5408\u6027\u667a\u6167\u7cfb\u7d71\u4f86\u89e3\u6c7a\u80fd\u6e90\u548c\u74b0\u5883\u554f\u984c\u7684\u6642\u6a5f\u5df2\u7d93\u6210\u719f\u3002  [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6204","post","type-post","status-publish","format-standard","hentry","category-global-environmental-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"IBM\u8a8d\u70ba\uff0cIT\u5728\u80fd\u6e90\u7ba1\u7406\u4e2d\u7684\u4f5c\u7528\u5df2\u7d93\u958b\u59cb\u9010\u6b65\u88ab\u8a8d\u53ef\uff0c\u63a1\u7528\u7d9c\u5408\u6027\u667a\u6167\u7cfb\u7d71\u4f86\u89e3\u6c7a\u80fd\u6e90\u548c\u74b0\u5883\u554f\u984c\u7684\u6642\u6a5f\u5df2\u7d93\u6210\u719f\u3002 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/it\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-12T11:19:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T07:00:04+00:00\" \/>\n<meta name=\"author\" content=\"tmp_jenyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"tmp_jenyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/\"},\"author\":{\"name\":\"tmp_jenyo\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\"},\"headline\":\"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c\",\"datePublished\":\"2010-03-12T11:19:17+00:00\",\"dateModified\":\"2024-02-02T07:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/\"},\"wordCount\":43,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/\",\"name\":\"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2010-03-12T11:19:17+00:00\",\"dateModified\":\"2024-02-02T07:00:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/global-environmental-news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\",\"name\":\"tmp_jenyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"caption\":\"tmp_jenyo\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/jenyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280","og_description":"IBM\u8a8d\u70ba\uff0cIT\u5728\u80fd\u6e90\u7ba1\u7406\u4e2d\u7684\u4f5c\u7528\u5df2\u7d93\u958b\u59cb\u9010\u6b65\u88ab\u8a8d\u53ef\uff0c\u63a1\u7528\u7d9c\u5408\u6027\u667a\u6167\u7cfb\u7d71\u4f86\u89e3\u6c7a\u80fd\u6e90\u548c\u74b0\u5883\u554f\u984c\u7684\u6642\u6a5f\u5df2\u7d93\u6210\u719f\u3002 [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/it\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2010-03-12T11:19:17+00:00","article_modified_time":"2024-02-02T07:00:04+00:00","author":"tmp_jenyo","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"tmp_jenyo","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/"},"author":{"name":"tmp_jenyo","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e"},"headline":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c","datePublished":"2010-03-12T11:19:17+00:00","dateModified":"2024-02-02T07:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/"},"wordCount":43,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u5168\u7403\u74b0\u4fdd\u6642\u4e8b"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/","url":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/","name":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2010-03-12T11:19:17+00:00","dateModified":"2024-02-02T07:00:04+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/it%e5%8f%af%e8%a7%a3%e5%86%b3%e8%83%bd%e6%ba%90%e8%88%87%e7%92%b0%e5%a2%83%e5%95%8f%e9%a1%8c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b","item":"https:\/\/li-on.biz\/category\/global-environmental-news\/"},{"@type":"ListItem","position":2,"name":"IT\u53ef\u89e3\u51b3\u80fd\u6e90\u8207\u74b0\u5883\u554f\u984c"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e","name":"tmp_jenyo","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","caption":"tmp_jenyo"},"url":"https:\/\/li-on.biz\/zh\/author\/jenyo\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/6204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=6204"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/6204\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=6204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=6204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=6204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}