{"id":6375,"date":"2010-10-12T19:47:13","date_gmt":"2010-10-12T11:47:13","guid":{"rendered":"https:\/\/li-on.biz\/?p=6375"},"modified":"2024-02-02T15:00:02","modified_gmt":"2024-02-02T07:00:02","slug":"%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/","title":{"rendered":"\u7f8e\u56fdTSCA\u6539\u9769\u4e3e\u884c\u542c\u8bc1\u4f1a"},"content":{"rendered":"<p>\u7f8e\u56fd\u4f17\u8bae\u9662\u7684\u5546\u4e1a\u3001\u8d38\u6613\u548c\u6d88\u8d39\u8005\u4fdd\u62a4\u59d4\u5458\u4f1a\u4e8e2010\u5e747\u6708\u672b\u4e3e\u884c\u4e86\u300a\u6709\u6bd2\u7269\u8d28\u63a7\u5236\u6cd5\u6848\u300b\uff08TSCA\uff09\u6539\u9769\u7684\u7b2c\u4e00\u8f6e\u542c\u8bc1\u4f1a\u3002\u542c\u8bc1\u4f1a\u4e0a\uff0c\u8bae\u5458\u5bf9\u300a2010\u6709\u6bd2\u5316\u5b66\u54c1\u5b89\u5168\u6cd5\u6848\u300b\u8fdb\u884c\u4e86\u4ecb\u7ecd\u3002<br><\/p>\n\n\n\n<p>Bobby L.Rush\u5728\u9648\u8ff0\u6f14\u8bb2\u4e2d\u6307\u51fa\uff1a\u63a8\u51fa\u7684TSCA\u6539\u9769\u5e76\u4e0d\u6307\u671b\u5404\u65b9\u90fd\u6ee1\u610f\uff0c\u4f46\u662f\u6709\u4e00\u70b9\u975e\u5e38\u660e\u786e\uff0c\u5373\u7f8e\u56fd\u6c11\u4f17\u6bd4\u8fc7\u53bb\u66f4\u52a0\u5e0c\u671b\u3001\u9700\u8981\u548c\u8981\u6c42\u77e5\u9053\u4ed6\u4eec\u6d88\u8d39\u7684\u4ea7\u54c1\u3001\u98df\u7269\u548c\u6c34\u3001\u4f4f\u623f\u3001\u5468\u56f4\u73af\u5883\u4e2d\u7684\u5316\u5b66\u54c1\u60c5\u51b5\u3002\u5e76\u4e14\u4ed6\u4eec\u8981\u6c42\u77e5\u9053\u5176\u5173\u8054\u7684\u4f7f\u7528\u3001\u5371\u5bb3\u548c\u66b4\u9732\u98ce\u9669\u3002<br><\/p>\n\n\n\n<p>\u53c2\u52a0\u542c\u8bc1\u4f1a\u7684\u4e1a\u754c\u4ee3\u8868\u5bf9TSCA\u7684\u6539\u9769\u8868\u793a\u5173\u6ce8\uff0c\u800cNGO\u56e2\u4f53\u5219\u5bf9\u6b64\u8868\u793a\u8d5e\u540c\u3002<br><\/p>\n\n\n\n<p>\u636e\u6089\uff0c\u73b0\u884c\u7684\u7f8e\u56fd\u7ba1\u63a7\u6709\u5bb3\u7269\u8d28\u7684\u6cd5\u5f8b\u4e3a1976\u5e74\u751f\u6548\u7684\u300a\u6709\u6bd2\u7269\u8d28\u63a7\u5236\u6cd5\u6848\u300b\uff0c\u4f46\u662f\u5176\u9881\u5e03\u5e74\u5934\u8fc7\u4e8e\u4e45\u8fdc\uff0c\u7f8e\u56fd\u653f\u5e9c\u53ca\u6c11\u4f17\u7686\u8ba4\u4e3a\u76ee\u524dTSCA\u5df2\u7ecf\u4e0d\u80fd\u5c65\u884c\u5176\u76ee\u7684\uff0c\u4ece2009\u5e74\u5f00\u59cb\uff0c\u7f8e\u56fd\u653f\u5e9c\u5c31\u6709\u610f\u5bf9TSCA\u8fdb\u884c\u6539\u9769\u3002\u57282010\u5e747\u670822\u65e5\uff0c\u8bae\u5458Rush\u00a0\u548cWaxman\u7b49\u4eba\u5f15\u5165\u4e86\u300a2010\u6709\u6bd2\u5316\u5b66\u54c1\u5b89\u5168\u6cd5\u6848\u300b\uff0c\u4fee\u8ba2TSCA\u3002<br><\/p>\n\n\n\n<p>\u300a2010\u6709\u6bd2\u5316\u5b66\u54c1\u5b89\u5168\u6cd5\u6848\u300b\u7684\u4e3b\u8981\u5185\u5bb9\u662f\u642d\u5efa\u4e00\u4e2a\u98ce\u9669\u4e3a\u57fa\u7840\u7684\u6846\u67b6\u6765\u4fdd\u8bc1\u6240\u6709\u5bf9\u6c11\u4f17\u6709\u66b4\u9732\u98ce\u9669\u7684\u5316\u5b66\u54c1\u90fd\u662f\u5b89\u5168\u548c\u4e25\u683c\u7ba1\u63a7\u7684\u3002\u4e1a\u754c\u88ab\u8981\u6c42\u63d0\u4f9b\u7ed9\u7f8e\u56fd\u73af\u4fdd\u5c40\uff08EPA\uff09\u4fe1\u606f\u3002\u300a2010\u6709\u6bd2\u5316\u5b66\u54c1\u5b89\u5168\u6cd5\u6848\u300b\u53ef\u80fd\u5c06\u6388\u6743EPA\u8c41\u514d\u67d0\u4e9b\u5df2\u77e5\u7684\u3001\u5b89\u5168\u7684\u5316\u5b66\u54c1\u6ee1\u8db3\u6cd5\u6848\u7684\u4e00\u4e9b\u8981\u6c42\uff0c\u540c\u65f6\u53ef\u80fd\u6307\u6d3eEPA\u57fa\u4e8e\u73b0\u6709\u7684\u6570\u636e\u6765\u786e\u5b9a\u4f18\u5148\u5ba1\u67e5\u7684\u7269\u8d28\u3002\u5982\u679c\u5fc5\u8981\uff0c\u8fd8\u53ef\u80fd\u6388\u6743EPA\u5f3a\u5236\u6d4b\u8bd5\u7684\u6743\u5229\u3002\u300a2010\u6709\u6bd2\u5316\u5b66\u54c1\u5b89\u5168\u6cd5\u6848\u300b\u8fd8\u5c06\u5f15\u5165\u6fc0\u52b1\u673a\u5236\uff0c\u9f13\u52b1\u7eff\u8272\u5316\u5b66\u3002\u5316\u5b66\u5236\u9020\u5546\u548c\u4e2d\u95f4\u5236\u9020\u5546\u5c06\u88ab\u8981\u6c42\u5411\u5176\u4e0b\u6e38\u7528\u6237\u63d0\u4f9b\u76f8\u5e94\u7684\u5316\u5b66\u54c1\u5b89\u5168\u7684\u57fa\u672c\u4fe1\u606f\u4ee5\u4fdd\u8bc1\u4ed6\u4eec\u80fd\u9009\u62e9\u66f4\u4e3a\u5b89\u5168\u7684\u6750\u6599\u3002\u6b64\u5916\uff0c\u5bf9\u4e8e\u6301\u4e45\u6027\u3001\u751f\u7269\u7d2f\u79ef\u6027\u548c\u6bd2\u6027\u7269\u8d28\uff08PBT\uff09\uff0c\u8be5\u6cd5\u6848\u8fd8\u5c06\u5efa\u7acb\u5bf9EPA\u7684\u7d27\u6025\u673a\u5236\u4ee5\u51cf\u5c11\u5176\u66b4\u9732\u98ce\u9669\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>\u7f8e\u570b\u773e\u8b70\u9662\u7684\u5546\u696d\u3001\u8cbf\u6613\u548c\u6d88\u8cbb\u8005\u4fdd\u8b77\u59d4\u54e1\u6703\u65bc2010\u5e747\u6708\u672b\u8209\u884c\u4e86\u300a\u6709\u6bd2\u7269\u8cea\u63a7\u5236\u6cd5\u6848\u300b\uff08TSCA\uff09\u6539\u9769\u7684\u7b2c\u4e00\u8f2a\u807d [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6375","post","type-post","status-publish","format-standard","hentry","category-global-environmental-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"\u7f8e\u570b\u773e\u8b70\u9662\u7684\u5546\u696d\u3001\u8cbf\u6613\u548c\u6d88\u8cbb\u8005\u4fdd\u8b77\u59d4\u54e1\u6703\u65bc2010\u5e747\u6708\u672b\u8209\u884c\u4e86\u300a\u6709\u6bd2\u7269\u8cea\u63a7\u5236\u6cd5\u6848\u300b\uff08TSCA\uff09\u6539\u9769\u7684\u7b2c\u4e00\u8f2a\u807d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/\u7f8e\u570btsca\u6539\u9769\u8209\u884c\u807d\u8b49\u6703\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-12T11:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T07:00:02+00:00\" \/>\n<meta name=\"author\" content=\"tmp_jenyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"tmp_jenyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/\"},\"author\":{\"name\":\"tmp_jenyo\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\"},\"headline\":\"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703\",\"datePublished\":\"2010-10-12T11:47:13+00:00\",\"dateModified\":\"2024-02-02T07:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/\"},\"wordCount\":22,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/\",\"name\":\"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2010-10-12T11:47:13+00:00\",\"dateModified\":\"2024-02-02T07:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/global-environmental-news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\",\"name\":\"tmp_jenyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"caption\":\"tmp_jenyo\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/jenyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280","og_description":"\u7f8e\u570b\u773e\u8b70\u9662\u7684\u5546\u696d\u3001\u8cbf\u6613\u548c\u6d88\u8cbb\u8005\u4fdd\u8b77\u59d4\u54e1\u6703\u65bc2010\u5e747\u6708\u672b\u8209\u884c\u4e86\u300a\u6709\u6bd2\u7269\u8cea\u63a7\u5236\u6cd5\u6848\u300b\uff08TSCA\uff09\u6539\u9769\u7684\u7b2c\u4e00\u8f2a\u807d [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/\u7f8e\u570btsca\u6539\u9769\u8209\u884c\u807d\u8b49\u6703\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2010-10-12T11:47:13+00:00","article_modified_time":"2024-02-02T07:00:02+00:00","author":"tmp_jenyo","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"tmp_jenyo","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/"},"author":{"name":"tmp_jenyo","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e"},"headline":"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703","datePublished":"2010-10-12T11:47:13+00:00","dateModified":"2024-02-02T07:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/"},"wordCount":22,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u5168\u7403\u74b0\u4fdd\u6642\u4e8b"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/","url":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/","name":"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703 - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2010-10-12T11:47:13+00:00","dateModified":"2024-02-02T07:00:02+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/%e7%be%8e%e5%9c%8btsca%e6%94%b9%e9%9d%a9%e8%88%89%e8%a1%8c%e8%81%bd%e8%ad%89%e6%9c%83\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b","item":"https:\/\/li-on.biz\/category\/global-environmental-news\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u570bTSCA\u6539\u9769\u8209\u884c\u807d\u8b49\u6703"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e","name":"tmp_jenyo","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","caption":"tmp_jenyo"},"url":"https:\/\/li-on.biz\/zh\/author\/jenyo\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/6375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=6375"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/6375\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=6375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=6375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=6375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}