{"id":7646,"date":"2021-06-21T23:50:45","date_gmt":"2021-06-21T15:50:45","guid":{"rendered":"https:\/\/li-on.biz\/?p=7646"},"modified":"2024-02-02T14:59:09","modified_gmt":"2024-02-02T06:59:09","slug":"%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/","title":{"rendered":"\u82f1\u633a\u7eff\u80fd \u62df2030\u7981\u552e\u71c3\u6cb9\u8f66"},"content":{"rendered":"<p>\u82f1\u56fd\u5a92\u4f53\u62a5\u5bfc\uff0c\u82f1\u56fd\u9996\u76f8\u5f3a\u751f\u9884\u5b9a\u572818\u65e5\u63d0\u51fa\u7eff\u80fd\u8ba1\u753b\uff0c\u53ef\u80fd\u5ba3\u5e03\u4ece2030\u5e74\u8d77\u7981\u552e\u4ee5\u6c7d\u6cb9\u4e0e\u67f4\u6cb9\u4e3a\u71c3\u6599\u9a71\u52a8\u7684\u6c7d\u8f66\uff0c\u6bd4\u539f\u5b9a\u65f6\u95f4\u63d0\u524d5\u5e74\uff0c\u8fd9\u662f\u5f3a\u751f\u7b2c\u4e8c\u5ea6\u63d0\u524d\u7981\u552e\u4ee4\u7684\u65f6\u95f4\uff0c\u51f8\u663e\u82f1\u56fd\u8fbe\u6210\u51c0\u96f6\u78b3\u6392\u76ee\u6807\u7684\u51b3\u5fc3\u3002 \u82f1\u56fd\u5e7f\u64ad\u516c\u53f8\uff08BBC\uff09\u4e0e\u91d1\u878d\u65f6\u62a5\uff08FT\uff09\u62a5\u5bfc\uff0c\u82f1\u56fd\u5bf9\u6c7d\u3001\u67f4\u6cb9\u8f66\u7684\u7981\u552e\u4ee4\u53ef\u80fd\u63d0\u524d\u81f32030\u5e74\uff0c\u5e76\u4e8e2035\u5e74\u7981\u552e\u6cb9\u7535\u6df7\u5408\u8f66\u3002\u77e5\u60c5\u4eba\u58eb\u900f\u9732\uff0c\u82f1\u56fd\u653f\u5e9c\u5c1a\u672a\u505a\u51fa\u6700\u540e\u51b3\u5b9a\u3002 \u82f1\u56fd\u539f\u5b9a2040\u5e74\u8d77\u5b9e\u65bd\u6c7d\u3001\u67f4\u6cb9\u8f66\u7981\u552e\u4ee4\uff0c\u4e4b\u540e\u5f3a\u751f\u4eca\u5e742\u6708\u5ba3\u5e03\uff0c\u7981\u552e\u4ee4\u5c06\u63d0\u524d\u81f32035\u5e74\u3002\u5982\u4eca\u5f3a\u751f\u53ef\u80fd\u4f1a\u518d\u5ea6\u628a\u7981\u552e\u4ee4\u7684\u65f6\u95f4\u63d0\u524d\u81f32030\u5e74\uff0c\u6b64\u4e3e\u662f\u82f1\u56fd\u7eff\u80fd\u8ba1\u753b\u7684\u4e00\u73af\uff1b\u5f3a\u751f\u653f\u5e9c\u81f3\u5c11\u5df2\u4e24\u5ea6\u5ef6\u540e\u53d1\u5e03\u8fd9\u9879\u8ba1\u753b\u7684\u65f6\u95f4\u3002 \u77e5\u60c5\u4eba\u58eb\u8868\u793a\uff0c\u5f3a\u751f\u6392\u5b9a\u572818\u65e5\u516c\u5e03\u7eff\u80fd\u8ba1\u753b\uff0c\u5c06\u805a\u7126\u4e8e\u6c22\u80fd\u3001\u78b3\u6355\u6349\u4e0e\u50a8\u5b58\u3001\u79bb\u5cb8\u98ce\u7535\u53ca\u623f\u5c4b\u9694\u70ed\uff0c\u9884\u6599\u4ed6\u5c06\u6279\u51c6\u5174\u5efaSizewell\u7b49\u6838\u7535\u5382\uff0c\u5e76\u6295\u8d44\u5c0f\u578b\u6a21\u7ec4\u5316\u53cd\u5e94\u7089\uff08SMR\uff09\u3002\u8fd9\u4e9b\u90fd\u662f\u51cf\u5c11\u6c61\u67d3\u7684\u5173\u952e\u6280\u672f\uff0c\u4f46\u82e5\u653f\u5e9c\u672a\u63d0\u4f9b\u8865\u52a9\uff0c\u6210\u672c\u8fc7\u4e8e\u9ad8\u6602\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>\u82f1\u570b\u5a92\u9ad4\u5831\u5c0e\uff0c\u82f1\u570b\u9996\u76f8\u5f37\u751f\u9810\u5b9a\u572818\u65e5\u63d0\u51fa\u7da0\u80fd\u8a08\u756b\uff0c\u53ef\u80fd\u5ba3\u5e03\u5f9e2030\u5e74\u8d77\u7981\u552e\u4ee5\u6c7d\u6cb9\u8207\u67f4\u6cb9\u70ba\u71c3\u6599\u9a45\u52d5\u7684\u6c7d\u8eca\uff0c\u6bd4 [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7646","post","type-post","status-publish","format-standard","hentry","category-global-environmental-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"\u82f1\u570b\u5a92\u9ad4\u5831\u5c0e\uff0c\u82f1\u570b\u9996\u76f8\u5f37\u751f\u9810\u5b9a\u572818\u65e5\u63d0\u51fa\u7da0\u80fd\u8a08\u756b\uff0c\u53ef\u80fd\u5ba3\u5e03\u5f9e2030\u5e74\u8d77\u7981\u552e\u4ee5\u6c7d\u6cb9\u8207\u67f4\u6cb9\u70ba\u71c3\u6599\u9a45\u52d5\u7684\u6c7d\u8eca\uff0c\u6bd4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/\u82f1\u633a\u7da0\u80fd-\u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T15:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T06:59:09+00:00\" \/>\n<meta name=\"author\" content=\"tmp_jenyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"tmp_jenyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/\"},\"author\":{\"name\":\"tmp_jenyo\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\"},\"headline\":\"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca\",\"datePublished\":\"2021-06-21T15:50:45+00:00\",\"dateModified\":\"2024-02-02T06:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/\",\"name\":\"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2021-06-21T15:50:45+00:00\",\"dateModified\":\"2024-02-02T06:59:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/global-environmental-news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\",\"name\":\"tmp_jenyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"caption\":\"tmp_jenyo\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/jenyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280","og_description":"\u82f1\u570b\u5a92\u9ad4\u5831\u5c0e\uff0c\u82f1\u570b\u9996\u76f8\u5f37\u751f\u9810\u5b9a\u572818\u65e5\u63d0\u51fa\u7da0\u80fd\u8a08\u756b\uff0c\u53ef\u80fd\u5ba3\u5e03\u5f9e2030\u5e74\u8d77\u7981\u552e\u4ee5\u6c7d\u6cb9\u8207\u67f4\u6cb9\u70ba\u71c3\u6599\u9a45\u52d5\u7684\u6c7d\u8eca\uff0c\u6bd4 [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/\u82f1\u633a\u7da0\u80fd-\u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2021-06-21T15:50:45+00:00","article_modified_time":"2024-02-02T06:59:09+00:00","author":"tmp_jenyo","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"tmp_jenyo","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/"},"author":{"name":"tmp_jenyo","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e"},"headline":"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca","datePublished":"2021-06-21T15:50:45+00:00","dateModified":"2024-02-02T06:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u5168\u7403\u74b0\u4fdd\u6642\u4e8b"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/","url":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/","name":"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2021-06-21T15:50:45+00:00","dateModified":"2024-02-02T06:59:09+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/%e8%8b%b1%e6%8c%ba%e7%b6%a0%e8%83%bd-%e6%93%ac2030%e7%a6%81%e5%94%ae%e7%87%83%e6%b2%b9%e8%bb%8a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b","item":"https:\/\/li-on.biz\/category\/global-environmental-news\/"},{"@type":"ListItem","position":2,"name":"\u82f1\u633a\u7da0\u80fd \u64ec2030\u7981\u552e\u71c3\u6cb9\u8eca"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e","name":"tmp_jenyo","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","caption":"tmp_jenyo"},"url":"https:\/\/li-on.biz\/zh\/author\/jenyo\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/7646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=7646"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/7646\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=7646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=7646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=7646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}