{"id":7664,"date":"2021-06-21T23:54:31","date_gmt":"2021-06-21T15:54:31","guid":{"rendered":"https:\/\/li-on.biz\/?p=7664"},"modified":"2024-02-02T14:59:08","modified_gmt":"2024-02-02T06:59:08","slug":"%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2","status":"publish","type":"post","link":"https:\/\/li-on.biz\/zh\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/","title":{"rendered":"\u5faa\u73af\u7ecf\u6d4e\u5c55\u767b\u573a \u4e2d\u5c0f\u4f01\u4e1a\u6c38\u7eed\u5faa\u73af\u8865\u7ed9\u7ad9\u79c0\u6c38\u7eed\u4ea7\u54c1"},"content":{"rendered":"<p>\u300cTASS 2020\u4e9a\u6d32\u6c38\u7eed\u4f9b\u5e94+\u5faa\u73af\u7ecf\u6d4e\u4f1a\u5c55\u300d\u4eca(2)\u65e5\u5728\u9ad8\u96c4\u5c55\u89c8\u9986\u767b\u573a\uff0c\u7ecf\u6d4e\u90e8\u4e2d\u5c0f\u4f01\u4e1a\u5904\u4e3a\u5c55\u73b0\u6211\u56fd\u4e2d\u5c0f\u4f01\u4e1a\u5728\u5faa\u73af\u7ecf\u6d4e\u4e0e\u7eff\u8272\u6c38\u7eed\u53d1\u5c55\u7684\u4eae\u773c\u8868\u73b0\uff0c\u7279\u522b\u89c4\u5212\u8bbe\u7f6e\u300c\u4e2d\u5c0f\u4f01\u4e1a\u6c38\u7eed\u5faa\u73af\u8865\u7ed9\u7ad9\u300d\uff0c\u9664\u9080\u8bf7\u672c\u5e749\u5bb6\u8f85\u5bfc\u4e1a\u8005\u5c55\u51fa\u521b\u65b0\u7eff\u8272\u4ea7\u54c1\u4e0e\u5546\u4e1a\u6a21\u5f0f\uff0c\u5e76\u7531\u4e2d\u5c0f\u4f01\u4e1a\u5904\u4e3a\u4e1a\u8005\u6388\u8bc1\u9881\u5956\u3002 \u7ecf\u6d4e\u90e8\u4e2d\u5c0f\u4f01\u4e1a\u5904\u7ec4\u957f\u9ec4\u96c5\u840d(\u524d\u6392\u53f3\u56db\u8d77)\u3001\u5851\u80f6\u4e2d\u5fc3\u603b\u7ecf\u7406\u8427\u8000\u8d35\uff0c\u4e0e9\u5bb6\u53d7\u8bc1\u4e1a\u8005\u5408\u2026 \u7ecf\u6d4e\u90e8\u4e2d\u5c0f\u4f01\u4e1a\u5904\u7ec4\u957f\u9ec4\u96c5\u840d(\u524d\u6392\u53f3\u56db\u8d77)\u3001\u5851\u80f6\u4e2d\u5fc3\u603b\u7ecf\u7406\u8427\u8000\u8d35\uff0c\u4e0e9\u5bb6\u53d7\u8bc1\u4e1a\u8005\u5408\u5f71\u3002 \u5851\u80f6\u4e2d\u5fc3\u5345\u6444\u5f71 \u4e2d\u5c0f\u4f01\u4e1a\u5904\u7ec4\u957f\u9ec4\u96c5\u840d\u81f4\u8bcd\u8868\u793a\uff0c\u5168\u7403\u6bcf\u5e74\u67091\u5343\u4ebf\u5428\u7684\u5929\u7136\u8d44\u6e90\u88ab\u635f\u8017\uff0c\u5176\u4e2d\u6709\u4e5d\u6210\u672a\u88ab\u56de\u6536\u518d\u5229\u7528\uff0c\u663e\u793a\u5faa\u73af\u518d\u5229\u7528\u6709\u6781\u5927\u7684\u53d1\u5c55\u6f5c\u529b\u3002\u5c24\u5176\uff0c\u7f8e\u4e2d\u8d38\u6613\u4e0e\u75ab\u60c5\u51b2\u51fb\u4e2d\u5c0f\u4f01\u4e1a\u7684\u8425\u8fd0\uff0c\u4e1a\u8005\u5982\u4f55\u521b\u65b0\u8425\u8fd0\u6a21\u5f0f\uff0c\u7279\u522b\u662f\u5982\u4f55\u671d\u7eff\u8272\u521b\u65b0\u4e4b\u8def\u8fc8\u8fdb\uff0c\u63d0\u5347\u4ea7\u54c1\u9644\u52a0\u4ef7\u503c\uff0c\u8fdb\u800c\u4e0e\u56fd\u9645\u63a5\u8f68\uff0c\u662f\u4e2d\u5c0f\u4f01\u4e1a\u5fc5\u987b\u6b63\u89c6\u4e0e\u52aa\u529b\u7684\u65b9\u5411\u3002\u9ec4\u96c5\u840d\u6307\u51fa\uff0c\u4f01\u4e1a\u4f9d\u5faa\u56fd\u9645\u5faa\u73af\u6807\u51c6\u5e76\u5c06\u7eff\u8272\u6c38\u7eed\u67b6\u6784\u4e0e\u6982\u5ff5\u7eb3\u5165\u8425\u8fd0\u6a21\u5f0f\u5df2\u4e3a\u8d8b\u52bf\uff0c\u900f\u8fc7\u5bf9\u5404\u56fd\u4f01\u4e1a\u5faa\u73af\u7ecf\u6d4e\u7684\u7ecf\u9a8c\u4e0e\u4f18\u52bf\u5206\u4eab\uff0c\u80fd\u542f\u53d1\u53f0\u6e7e\u4e2d\u5c0f\u4f01\u4e1a\u6301\u7eed\u521b\u65b0\u7684\u5faa\u73af\u7ecf\u6d4e\u8425\u8fd0\u6a21\u5f0f\uff0c\u8fdb\u800c\u8fdb\u519b\u56fd\u9645\u5e02\u573a\uff0c\u642d\u8f68\u5168\u7403\u7eff\u8272\u5546\u673a\u3002 \u5947\u7acb\u5b9e\u4e1a\u5c55\u51fa\u300c\u6ee4\u5fae\u5c18\u7c92\u98ce\u673a\u8bbe\u5907(FFU)\u76d1\u63a7\u7cfb\u7edf\u300d\u3002 \u6768\u806a\u6865\u5345\u6444\u5f71 \u5947\u7acb\u5b9e\u4e1a\u5c55\u51fa\u300c\u6ee4\u5fae\u5c18\u7c92\u98ce\u673a\u8bbe\u5907(FFU)\u76d1\u63a7\u7cfb\u7edf\u300d\u3002 \u6768\u806a\u6865\u5345\u6444\u5f71 \u300c\u4e2d\u5c0f\u4f01\u4e1a\u6c38\u7eed\u5faa\u73af\u8865\u7ed9\u7ad9\u300d\u5171\u9080\u8bf7\u76ca\u5927\u7406\u7814\u3001\u5947\u7acb\u5b9e\u4e1a\u3001\u9f99\u749e\u7eff\u80fd\u3001\u777f\u6cfd\u4f01\u4e1a\u3001\u963f\u98de\u56fd\u9645\u3001\u5927\u80fd\u751f\u7269\u79d1\u6280\u3001\u4e54\u798f\u6750\u6599\u3001\u5982\u79be\u6c38\u7eed\u6587\u521b\u3001\u4e0a\u54c1\u738b\u98df\u54c1\u7b499\u5bb6\u53d7\u8f85\u5bfc\u4e1a\u8005\u53c2\u5c55\uff0c\u5206\u522b\u5c55\u51fa\u5229\u7528\u56de\u6536\u6216\u5e9f\u5f03\u7269\u505a\u6210\u7684\u7eff\u8272\u4ea7\u54c1\uff0c\u5305\u62ec\u5229\u7528\u7267\u573a\u9e21\u7caa\u3001\u5e9f\u6c34\u4ea7\u751f\u6cbc\u6c14\u53d1\u7535\uff1b\u889c\u978b\u56de\u6536\u7c89\u788e\u518d\u5236\uff0c\u964d\u4f4e\u65b0\u6599\u4f7f\u7528\uff1b\u5e9f\u5f03\u8863\u6750\u5347\u7ea7\u518d\u5236\u6210\u5168\u65b0\u670d\u9970\uff1b\u5e94\u7528\u519c\u6797\u5e9f\u5f03\u7269\u4fc3\u8fdb\u9999\u6c1b\u4ea7\u4e1a\u51cf\u78b3\u964d\u5851\uff1b\u5e9f\u5f03\u8c46\u6e23\u591a\u5143\u518d\u5229\u7528\uff0c\u63d0\u5347\u7ecf\u6d4e\u4ef7\u503c\uff1b\u5f00\u53d1\u9999\u82b1\u683c\u5916\u54c1\u6210\u521b\u65b0\u98df\u54c1\u539f\u6599\uff0c\u51cf\u5c11\u5e9f\u5f03\uff1b\u5c06\u519c\u4e1a\u5269\u4f59\u8d44\u6750\u80fd\u6e90\u5316\uff0c\u51cf\u5c11\u5e9f\u5f03\u53ca\u78b3\u6392\u653e\uff1b\u5f00\u53d1\u53ef\u751f\u7269\u5206\u89e3\u8584\u819c\uff0c\u4f7f\u83c7\u888b\u53ef\u53d8\u6210\u6709\u673a\u8d28\u5806\u80a5\uff1b\u8f6c\u5316\u4e0e\u6574\u5408FFU\u76d1\u63a7\u7cfb\u7edf\uff0c\u964d\u4f4e\u4ea7\u4e1a\u80fd\u6e90\u6d88\u8017\u7b49\u3002 \u76ca\u5927\u7406\u7814\u5c55\u51fa\u5229\u7528\u8c46\u6e23\u505a\u6210\u7684\u7d20\u98df\u4ea7\u54c1\u4e0e\u755c\u7267\u9972\u6599\u3002 \u6768\u806a\u6865\/\u6444\u5f71 \u76ca\u5927\u7406\u7814\u5c55\u51fa\u5229\u7528\u8c46\u6e23\u505a\u6210\u7684\u7d20\u98df\u4ea7\u54c1\u4e0e\u755c\u7267\u9972\u6599\u3002 \u6768\u806a\u6865\/\u6444\u5f71 \u540c\u65f6\uff0c\u5373\u5c06\u4e8e12\u67089\u65e5\u6b63\u5f0f\u5f00\u5e55\u7684\u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\uff0c\u4e5f\u4ee5\u6d53\u7f29\u7cbe\u534e\u7248\u7684\u65b9\u5f0f\u62a2\u5148\u5728\u5c55\u573a\u66dd\u5149\uff0c\u5c55\u73b0\u591a\u79cd\u4f4e\u5371\u5bb3\u3001\u7701\u80fd\u8d44\u6e90\u3001\u6613\u56de\u6536\u7684\u6c38\u7eed\u6750\u8d28\uff0c\u8ba9\u53c2\u89c2\u6765\u5bbe\u4e86\u89e3\u5404\u79cd\u6750\u8d28\u7684\u6765\u6e90\u4e0e\u4f7f\u7528\u65b9\u5f0f\u3002 \u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\u8bbe\u4e8e\u53f0\u4e2d\u5851\u80f6\u5de5\u4e1a\u6280\u672f\u53d1\u5c55\u4e2d\u5fc3\uff0c\u9664\u5b9e\u4f53\u5c55\u793a\u5916\uff0c\u4e5f\u8bbe\u6709\u7ebf\u4e0a\u8d44\u6599\u5e93\uff0c\u671f\u85c9\u7531\u591a\u5143\u6750\u8d28\u8d44\u6e90\uff0c\u63d0\u4f9b\u4e2d\u5c0f\u4f01\u4e1a\u4e3b\u5f00\u542f\u7eff\u8272\u8bbe\u8ba1\u7684\u65b0\u53d1\u60f3\uff0c\u521b\u9020\u66f4\u591a\u6c38\u7eed\u5546\u54c1\u3002 \u8d22\u56e2\u6cd5\u4eba\u5851\u80f6\u4e2d\u5fc3\u603b\u7ecf\u7406\u8427\u8000\u8d35\u9488\u5bf9\u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\u7684\u529f\u80fd\u4e0e\u76ee\u6807\u8868\u793a\uff0c\u53f0\u6e7e\u767e\u5de5\u767e\u4e1a\u6f5c\u85cf\u4e0d\u5c11\u6c38\u7eed\u53d1\u5c55\u7684\u80fd\u91cf\uff0c\u5305\u62ec\u6750\u6599\u3001\u8bbe\u8ba1\u4e0e\u52a0\u5de5\u3002\u4ee5\u6750\u6599\u800c\u8a00\uff0c\u5f88\u591a\u56fd\u5bb6\u3001\u5f88\u591a\u4ea7\u4e1a\u4e0d\u77e5\u9053\u6c38\u7eed\u6750\u6599\u7684\u6765\u6e90\uff0c\u4e3a\u63d0\u4f9b\u4e00\u4e2a\u53ef\u4ee5\u54a8\u8be2\u3001\u4ea4\u6d41\u7684\u5e73\u53f0\uff0c\u56e0\u6b64\u5851\u80f6\u4e2d\u5fc3\u89c4\u5212\u8bbe\u7acb\u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\uff0c\u5c06\u57284\u5e74\u5185\u641c\u96c62,000\u79cd\u5177\u6c38\u7eed\u6027\u3001\u73af\u4fdd\u6027\u4e0e\u5faa\u73af\u6027\u4ef7\u503c\u7684\u6750\u6599\u3001\u534a\u6210\u54c1\u4e0e\u6210\u54c1\uff0c\u540c\u65f6\u642d\u914d\u7ebf\u4e0a\u8d44\u6599\u5e93\u7684\u8fd0\u7528\uff0c\u4e32\u8fde\u5236\u9020\u4f9b\u5e94\u4e0e\u8bbe\u8ba1\u7684\u9700\u6c42\uff0c\u501f\u6b64\u521b\u9020\u6c38\u7eed\u5faa\u73af\u7684\u5546\u673a\uff0c\u5e76\u63d0\u4f9b\u65b0\u521b\u3001\u751f\u4ea7\u5236\u9020\u4e0e\u4ea7\u4e1a\u8f6c\u578b\u7684\u5951\u673a\u3002 \u5851\u80f6\u4e2d\u5fc3\u603b\u7ecf\u7406\u8427\u8000\u8d35\u8bf4\u660e\u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\u7684\u529f\u80fd\u4e0e\u76ee\u6807\u3002 \u6768\u806a\u6865\/\u6444\u5f71 \u5851\u80f6\u4e2d\u5fc3\u603b\u7ecf\u7406\u8427\u8000\u8d35\u8bf4\u660e\u300c\u6c38\u7eed\u6750\u8d28\u56fe\u4e66\u9986\u300d\u7684\u529f\u80fd\u4e0e\u76ee\u6807\u3002 \u6768\u806a\u6865\/\u6444\u5f71<\/p>","protected":false},"excerpt":{"rendered":"<p>\u300cTASS 2020\u4e9e\u6d32\u6c38\u7e8c\u4f9b\u61c9+\u5faa\u74b0\u7d93\u6fdf\u6703\u5c55\u300d\u4eca(2)\u65e5\u5728\u9ad8\u96c4\u5c55\u89bd\u9928\u767b\u5834\uff0c\u7d93\u6fdf\u90e8\u4e2d\u5c0f\u4f01\u696d\u8655\u70ba\u5c55\u73fe\u6211\u570b\u4e2d\u5c0f\u4f01\u696d [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7664","post","type-post","status-publish","format-standard","hentry","category-global-environmental-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"og:description\" content=\"\u300cTASS 2020\u4e9e\u6d32\u6c38\u7e8c\u4f9b\u61c9+\u5faa\u74b0\u7d93\u6fdf\u6703\u5c55\u300d\u4eca(2)\u65e5\u5728\u9ad8\u96c4\u5c55\u89bd\u9928\u767b\u5834\uff0c\u7d93\u6fdf\u90e8\u4e2d\u5c0f\u4f01\u696d\u8655\u70ba\u5c55\u73fe\u6211\u570b\u4e2d\u5c0f\u4f01\u696d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/li-on.biz\/zh\/\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834-\u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7acb\u96cd\u79d1\u6280\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T15:54:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T06:59:08+00:00\" \/>\n<meta name=\"author\" content=\"tmp_jenyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"tmp_jenyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/\"},\"author\":{\"name\":\"tmp_jenyo\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\"},\"headline\":\"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1\",\"datePublished\":\"2021-06-21T15:54:31+00:00\",\"dateModified\":\"2024-02-02T06:59:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"articleSection\":[\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/\",\"name\":\"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\"},\"datePublished\":\"2021-06-21T15:54:31+00:00\",\"dateModified\":\"2024-02-02T06:59:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b\",\"item\":\"https:\\\/\\\/li-on.biz\\\/category\\\/global-environmental-news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#website\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"description\":\"\u7acb\u96cd\u79d1\u6280\u5be6\u696d\u6709\u9650\u516c\u53f8\",\"publisher\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/li-on.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#organization\",\"name\":\"\u7acb\u96cd\u79d1\u6280\",\"url\":\"https:\\\/\\\/li-on.biz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"contentUrl\":\"https:\\\/\\\/li-on.biz\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-cropped-lion-logo1.png\",\"width\":4065,\"height\":1355,\"caption\":\"\u7acb\u96cd\u79d1\u6280\"},\"image\":{\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/li-on.biz\\\/#\\\/schema\\\/person\\\/9b30a30a772fe5d7ab78466583b9045e\",\"name\":\"tmp_jenyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g\",\"caption\":\"tmp_jenyo\"},\"url\":\"https:\\\/\\\/li-on.biz\\\/zh\\\/author\\\/jenyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280","og_description":"\u300cTASS 2020\u4e9e\u6d32\u6c38\u7e8c\u4f9b\u61c9+\u5faa\u74b0\u7d93\u6fdf\u6703\u5c55\u300d\u4eca(2)\u65e5\u5728\u9ad8\u96c4\u5c55\u89bd\u9928\u767b\u5834\uff0c\u7d93\u6fdf\u90e8\u4e2d\u5c0f\u4f01\u696d\u8655\u70ba\u5c55\u73fe\u6211\u570b\u4e2d\u5c0f\u4f01\u696d [&hellip;]","og_url":"https:\/\/li-on.biz\/zh\/\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834-\u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\/","og_site_name":"\u7acb\u96cd\u79d1\u6280","article_published_time":"2021-06-21T15:54:31+00:00","article_modified_time":"2024-02-02T06:59:08+00:00","author":"tmp_jenyo","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"tmp_jenyo","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/#article","isPartOf":{"@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/"},"author":{"name":"tmp_jenyo","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e"},"headline":"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1","datePublished":"2021-06-21T15:54:31+00:00","dateModified":"2024-02-02T06:59:08+00:00","mainEntityOfPage":{"@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"articleSection":["\u5168\u7403\u74b0\u4fdd\u6642\u4e8b"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/","url":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/","name":"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1 - \u7acb\u96cd\u79d1\u6280","isPartOf":{"@id":"https:\/\/li-on.biz\/#website"},"datePublished":"2021-06-21T15:54:31+00:00","dateModified":"2024-02-02T06:59:08+00:00","breadcrumb":{"@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/li-on.biz\/%e5%be%aa%e7%92%b0%e7%b6%93%e6%bf%9f%e5%b1%95%e7%99%bb%e5%a0%b4-%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e6%b0%b8%e7%ba%8c%e5%be%aa%e7%92%b0%e8%a3%9c%e7%b5%a6%e7%ab%99%e7%a7%80%e6%b0%b8%e7%ba%8c%e7%94%a2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u5168\u7403\u74b0\u4fdd\u6642\u4e8b","item":"https:\/\/li-on.biz\/category\/global-environmental-news\/"},{"@type":"ListItem","position":2,"name":"\u5faa\u74b0\u7d93\u6fdf\u5c55\u767b\u5834 \u4e2d\u5c0f\u4f01\u696d\u6c38\u7e8c\u5faa\u74b0\u88dc\u7d66\u7ad9\u79c0\u6c38\u7e8c\u7522\u54c1"}]},{"@type":"WebSite","@id":"https:\/\/li-on.biz\/#website","url":"https:\/\/li-on.biz\/","name":"\u7acb\u96cd\u79d1\u6280","description":"\u7acb\u96cd\u79d1\u6280\u5b9e\u4e1a\u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/li-on.biz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/li-on.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/li-on.biz\/#organization","name":"\u7acb\u96cd\u79d1\u6280","url":"https:\/\/li-on.biz\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/","url":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","contentUrl":"https:\/\/li-on.biz\/wp-content\/uploads\/2023\/11\/cropped-cropped-lion-logo1.png","width":4065,"height":1355,"caption":"\u7acb\u96cd\u79d1\u6280"},"image":{"@id":"https:\/\/li-on.biz\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/li-on.biz\/#\/schema\/person\/9b30a30a772fe5d7ab78466583b9045e","name":"tmp_jenyo","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6c7d33651e8d3bfa1c1b25ca0ce76f71eb0b92bba73166c3e1bd0a73a672611?s=96&d=mm&r=g","caption":"tmp_jenyo"},"url":"https:\/\/li-on.biz\/zh\/author\/jenyo\/"}]}},"_links":{"self":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/7664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/comments?post=7664"}],"version-history":[{"count":0,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/posts\/7664\/revisions"}],"wp:attachment":[{"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/media?parent=7664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/categories?post=7664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/li-on.biz\/zh\/wp-json\/wp\/v2\/tags?post=7664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}